{"id":20246,"date":"2012-05-14T22:51:58","date_gmt":"2012-05-15T03:51:58","guid":{"rendered":"http:\/\/www.filmbuffonline.com\/FBOLNewsreel\/wordpress\/?p=20246"},"modified":"2018-12-08T15:31:06","modified_gmt":"2018-12-08T20:31:06","slug":"four-minute-amazing-spider-man-preview","status":"publish","type":"post","link":"https:\/\/www.filmbuffonline.com\/FBOLNewsreel\/wordpress\/2012\/05\/14\/four-minute-amazing-spider-man-preview\/","title":{"rendered":"Four Minute AMAZING SPIDER-MAN Preview"},"content":{"rendered":"<p><a href=\"http:\/\/www.filmbuffonline.com\/FBOLNewsreel\/wordpress\/wp-content\/uploads\/2012\/05\/AmazingSpiderManTrailer.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.filmbuffonline.com\/FBOLNewsreel\/wordpress\/wp-content\/uploads\/2012\/05\/AmazingSpiderManTrailer.jpg\" alt=\"\" title=\"AmazingSpiderManTrailer\" width=\"550\" height=\"265\" class=\"aligncenter size-full wp-image-20249\" srcset=\"https:\/\/www.filmbuffonline.com\/FBOLNewsreel\/wordpress\/wp-content\/uploads\/2012\/05\/AmazingSpiderManTrailer.jpg 550w, https:\/\/www.filmbuffonline.com\/FBOLNewsreel\/wordpress\/wp-content\/uploads\/2012\/05\/AmazingSpiderManTrailer-300x145.jpg 300w\" sizes=\"auto, (max-width: 550px) 100vw, 550px\" \/><\/a>Sony unveiled a new four minute preview of their upcoming <strong>Amazing Spider-Man<\/strong>. Although the second half plays out like a trailer, the first half offers what appears to be an edited down sequence of Spider-Man saving a boy whose life is threatened by the Lizard&#8217;s rampage. <\/p>\n<p>The second half features some more Spidey action as well as bit more of a look at poor Dr. Connors&#8217;s transformation into the Lizard. I&#8217;m not sure that I am thrilled that this continues to hint that there is a connection between Peter Parker and Dr. Connors and how each gained their powers. Connecting a hero&#8217;s and villain&#8217;s origins has become more than just a bit of a cliche. Hopefully director Marc Webb is bringing something new and fresh to that particular trope.<\/p>\n<p><iframe loading=\"lazy\" width=\"550\" height=\"309\" src=\"http:\/\/www.youtube.com\/embed\/16AwVWvjQhY\" frameborder=\"0\" allowfullscreen><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\">See Spidey save a kid and fight the Lizard.<\/div>\n<p> <a class=\"mh-excerpt-more\" href=\"https:\/\/www.filmbuffonline.com\/FBOLNewsreel\/wordpress\/2012\/05\/14\/four-minute-amazing-spider-man-preview\/\" title=\"Four Minute AMAZING SPIDER-MAN Preview\">[click for more]<\/a><\/p>\n","protected":false},"author":2,"featured_media":20249,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_ef_editorial_meta_date_first-draft-date":"","_ef_editorial_meta_paragraph_assignment":"","_ef_editorial_meta_checkbox_needs-photo":"","_ef_editorial_meta_number_word-count":"","footnotes":""},"categories":[84],"tags":[2394,3595],"series":[],"class_list":{"0":"post-20246","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-news","8":"tag-marc-webb","9":"tag-the-amazing-spider-man"},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"See Spidey save a kid and fight the Lizard.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Rich Drees\"\/>\n\t<meta name=\"google-site-verification\" content=\"wLC20yR0mPkWulQW1J3XdWt2N092dKXOxZCHsXSWa6A\" \/>\n\t<meta name=\"msvalidate.01\" content=\"7B67C6E6EDF5B3DC49380AB44DB9FDBF\" \/>\n\t<meta name=\"keywords\" content=\"the amazing spider-man,marc webb,movie news\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.filmbuffonline.com\/FBOLNewsreel\/wordpress\/2012\/05\/14\/four-minute-amazing-spider-man-preview\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"FilmBuffOnline\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Four Minute AMAZING SPIDER-MAN Preview\" \/>\n\t\t<meta property=\"og:description\" content=\"See Spidey save a kid and fight the Lizard.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.filmbuffonline.com\/FBOLNewsreel\/wordpress\/2012\/05\/14\/four-minute-amazing-spider-man-preview\/\" \/>\n\t\t<meta property=\"fb:app_id\" content=\"278369843542253\" \/>\n\t\t<meta property=\"fb:admins\" content=\"1588896122\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.filmbuffonline.com\/FBOLNewsreel\/wordpress\/wp-content\/uploads\/2012\/05\/AmazingSpiderManTrailer.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.filmbuffonline.com\/FBOLNewsreel\/wordpress\/wp-content\/uploads\/2012\/05\/AmazingSpiderManTrailer.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"550\" \/>\n\t\t<meta property=\"og:image:height\" content=\"265\" \/>\n\t\t<meta property=\"article:tag\" content=\"the amazing spider-man\" \/>\n\t\t<meta property=\"article:tag\" content=\"marc webb\" \/>\n\t\t<meta property=\"article:tag\" content=\"movie news\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2012-05-15T03:51:58+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2018-12-08T20:31:06+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/FilmBuffOnline\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/FilmBuffRich\/\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@FilmBuffOnLine\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Four Minute AMAZING SPIDER-MAN Preview\" \/>\n\t\t<meta name=\"twitter:description\" content=\"See Spidey save a kid and fight the Lizard.\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@FilmBuffRich\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.filmbuffonline.com\/FBOLNewsreel\/wordpress\/wp-content\/uploads\/2012\/05\/AmazingSpiderManTrailer.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.filmbuffonline.com\\\/FBOLNewsreel\\\/wordpress\\\/2012\\\/05\\\/14\\\/four-minute-amazing-spider-man-preview\\\/#article\",\"name\":\"Four Minute AMAZING SPIDER-MAN Preview\",\"headline\":\"Four Minute AMAZING SPIDER-MAN Preview\",\"author\":{\"@id\":\"https:\\\/\\\/www.filmbuffonline.com\\\/FBOLNewsreel\\\/wordpress\\\/author\\\/filmbuffrich\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.filmbuffonline.com\\\/FBOLNewsreel\\\/wordpress\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.filmbuffonline.com\\\/FBOLNewsreel\\\/wordpress\\\/wp-content\\\/uploads\\\/2012\\\/05\\\/AmazingSpiderManTrailer.jpg\",\"width\":550,\"height\":265},\"datePublished\":\"2012-05-14T22:51:58-04:00\",\"dateModified\":\"2018-12-08T15:31:06-05:00\",\"inLanguage\":\"en-US\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.filmbuffonline.com\\\/FBOLNewsreel\\\/wordpress\\\/2012\\\/05\\\/14\\\/four-minute-amazing-spider-man-preview\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.filmbuffonline.com\\\/FBOLNewsreel\\\/wordpress\\\/2012\\\/05\\\/14\\\/four-minute-amazing-spider-man-preview\\\/#webpage\"},\"articleSection\":\"Movie News, Marc Webb, The Amazing Spider-Man\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.filmbuffonline.com\\\/FBOLNewsreel\\\/wordpress\\\/2012\\\/05\\\/14\\\/four-minute-amazing-spider-man-preview\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.filmbuffonline.com\\\/FBOLNewsreel\\\/wordpress#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.filmbuffonline.com\\\/FBOLNewsreel\\\/wordpress\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.filmbuffonline.com\\\/FBOLNewsreel\\\/wordpress\\\/category\\\/news\\\/#listItem\",\"name\":\"Movie News\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.filmbuffonline.com\\\/FBOLNewsreel\\\/wordpress\\\/category\\\/news\\\/#listItem\",\"position\":2,\"name\":\"Movie News\",\"item\":\"https:\\\/\\\/www.filmbuffonline.com\\\/FBOLNewsreel\\\/wordpress\\\/category\\\/news\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.filmbuffonline.com\\\/FBOLNewsreel\\\/wordpress\\\/2012\\\/05\\\/14\\\/four-minute-amazing-spider-man-preview\\\/#listItem\",\"name\":\"Four Minute AMAZING SPIDER-MAN Preview\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.filmbuffonline.com\\\/FBOLNewsreel\\\/wordpress#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.filmbuffonline.com\\\/FBOLNewsreel\\\/wordpress\\\/2012\\\/05\\\/14\\\/four-minute-amazing-spider-man-preview\\\/#listItem\",\"position\":3,\"name\":\"Four Minute AMAZING SPIDER-MAN Preview\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.filmbuffonline.com\\\/FBOLNewsreel\\\/wordpress\\\/category\\\/news\\\/#listItem\",\"name\":\"Movie News\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.filmbuffonline.com\\\/FBOLNewsreel\\\/wordpress\\\/#organization\",\"name\":\"FilmBuffOnline\",\"description\":\"For The Complete Movie Fan\",\"url\":\"https:\\\/\\\/www.filmbuffonline.com\\\/FBOLNewsreel\\\/wordpress\\\/\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":2,\"maxValue\":6},\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.filmbuffonline.com\\\/FBOLNewsreel\\\/wordpress\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/FBOL-Reel.jpg\",\"@id\":\"https:\\\/\\\/www.filmbuffonline.com\\\/FBOLNewsreel\\\/wordpress\\\/2012\\\/05\\\/14\\\/four-minute-amazing-spider-man-preview\\\/#organizationLogo\",\"width\":250,\"height\":250},\"image\":{\"@id\":\"https:\\\/\\\/www.filmbuffonline.com\\\/FBOLNewsreel\\\/wordpress\\\/2012\\\/05\\\/14\\\/four-minute-amazing-spider-man-preview\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/FilmBuffOnline\",\"https:\\\/\\\/twitter.com\\\/FilmBuffOnLine\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/Filmbuffonline\\\/featured\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.filmbuffonline.com\\\/FBOLNewsreel\\\/wordpress\\\/author\\\/filmbuffrich\\\/#author\",\"url\":\"https:\\\/\\\/www.filmbuffonline.com\\\/FBOLNewsreel\\\/wordpress\\\/author\\\/filmbuffrich\\\/\",\"name\":\"Rich Drees\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.filmbuffonline.com\\\/FBOLNewsreel\\\/wordpress\\\/2012\\\/05\\\/14\\\/four-minute-amazing-spider-man-preview\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0374c2a69ae003ff0a1eed863d0eb2cb98777ffc58bc6e7bb66aeaeb36ca3308?s=96&d=mm&r=r\",\"width\":96,\"height\":96,\"caption\":\"Rich Drees\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/FilmBuffRich\\\/\",\"https:\\\/\\\/twitter.com\\\/FilmBuffRich\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.filmbuffonline.com\\\/FBOLNewsreel\\\/wordpress\\\/2012\\\/05\\\/14\\\/four-minute-amazing-spider-man-preview\\\/#webpage\",\"url\":\"https:\\\/\\\/www.filmbuffonline.com\\\/FBOLNewsreel\\\/wordpress\\\/2012\\\/05\\\/14\\\/four-minute-amazing-spider-man-preview\\\/\",\"name\":\"Four Minute AMAZING SPIDER-MAN Preview\",\"description\":\"See Spidey save a kid and fight the Lizard.\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.filmbuffonline.com\\\/FBOLNewsreel\\\/wordpress\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.filmbuffonline.com\\\/FBOLNewsreel\\\/wordpress\\\/2012\\\/05\\\/14\\\/four-minute-amazing-spider-man-preview\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.filmbuffonline.com\\\/FBOLNewsreel\\\/wordpress\\\/author\\\/filmbuffrich\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.filmbuffonline.com\\\/FBOLNewsreel\\\/wordpress\\\/author\\\/filmbuffrich\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.filmbuffonline.com\\\/FBOLNewsreel\\\/wordpress\\\/wp-content\\\/uploads\\\/2012\\\/05\\\/AmazingSpiderManTrailer.jpg\",\"@id\":\"https:\\\/\\\/www.filmbuffonline.com\\\/FBOLNewsreel\\\/wordpress\\\/2012\\\/05\\\/14\\\/four-minute-amazing-spider-man-preview\\\/#mainImage\",\"width\":550,\"height\":265},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.filmbuffonline.com\\\/FBOLNewsreel\\\/wordpress\\\/2012\\\/05\\\/14\\\/four-minute-amazing-spider-man-preview\\\/#mainImage\"},\"datePublished\":\"2012-05-14T22:51:58-04:00\",\"dateModified\":\"2018-12-08T15:31:06-05:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.filmbuffonline.com\\\/FBOLNewsreel\\\/wordpress\\\/#website\",\"url\":\"https:\\\/\\\/www.filmbuffonline.com\\\/FBOLNewsreel\\\/wordpress\\\/\",\"name\":\"FilmBuffOnline\",\"description\":\"For The Complete Movie Fan\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.filmbuffonline.com\\\/FBOLNewsreel\\\/wordpress\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Four Minute AMAZING SPIDER-MAN Preview<\/title>\n\n","aioseo_head_json":{"title":"Four Minute AMAZING SPIDER-MAN Preview","description":"See Spidey save a kid and fight the Lizard.","canonical_url":"https:\/\/www.filmbuffonline.com\/FBOLNewsreel\/wordpress\/2012\/05\/14\/four-minute-amazing-spider-man-preview\/","robots":"max-image-preview:large","keywords":"the amazing spider-man,marc webb,movie news","webmasterTools":{"google-site-verification":"wLC20yR0mPkWulQW1J3XdWt2N092dKXOxZCHsXSWa6A","msvalidate.01":"7B67C6E6EDF5B3DC49380AB44DB9FDBF","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.filmbuffonline.com\/FBOLNewsreel\/wordpress\/2012\/05\/14\/four-minute-amazing-spider-man-preview\/#article","name":"Four Minute AMAZING SPIDER-MAN Preview","headline":"Four Minute AMAZING SPIDER-MAN Preview","author":{"@id":"https:\/\/www.filmbuffonline.com\/FBOLNewsreel\/wordpress\/author\/filmbuffrich\/#author"},"publisher":{"@id":"https:\/\/www.filmbuffonline.com\/FBOLNewsreel\/wordpress\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/www.filmbuffonline.com\/FBOLNewsreel\/wordpress\/wp-content\/uploads\/2012\/05\/AmazingSpiderManTrailer.jpg","width":550,"height":265},"datePublished":"2012-05-14T22:51:58-04:00","dateModified":"2018-12-08T15:31:06-05:00","inLanguage":"en-US","mainEntityOfPage":{"@id":"https:\/\/www.filmbuffonline.com\/FBOLNewsreel\/wordpress\/2012\/05\/14\/four-minute-amazing-spider-man-preview\/#webpage"},"isPartOf":{"@id":"https:\/\/www.filmbuffonline.com\/FBOLNewsreel\/wordpress\/2012\/05\/14\/four-minute-amazing-spider-man-preview\/#webpage"},"articleSection":"Movie News, Marc Webb, The Amazing Spider-Man"},{"@type":"BreadcrumbList","@id":"https:\/\/www.filmbuffonline.com\/FBOLNewsreel\/wordpress\/2012\/05\/14\/four-minute-amazing-spider-man-preview\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.filmbuffonline.com\/FBOLNewsreel\/wordpress#listItem","position":1,"name":"Home","item":"https:\/\/www.filmbuffonline.com\/FBOLNewsreel\/wordpress","nextItem":{"@type":"ListItem","@id":"https:\/\/www.filmbuffonline.com\/FBOLNewsreel\/wordpress\/category\/news\/#listItem","name":"Movie News"}},{"@type":"ListItem","@id":"https:\/\/www.filmbuffonline.com\/FBOLNewsreel\/wordpress\/category\/news\/#listItem","position":2,"name":"Movie News","item":"https:\/\/www.filmbuffonline.com\/FBOLNewsreel\/wordpress\/category\/news\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.filmbuffonline.com\/FBOLNewsreel\/wordpress\/2012\/05\/14\/four-minute-amazing-spider-man-preview\/#listItem","name":"Four Minute AMAZING SPIDER-MAN Preview"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.filmbuffonline.com\/FBOLNewsreel\/wordpress#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.filmbuffonline.com\/FBOLNewsreel\/wordpress\/2012\/05\/14\/four-minute-amazing-spider-man-preview\/#listItem","position":3,"name":"Four Minute AMAZING SPIDER-MAN Preview","previousItem":{"@type":"ListItem","@id":"https:\/\/www.filmbuffonline.com\/FBOLNewsreel\/wordpress\/category\/news\/#listItem","name":"Movie News"}}]},{"@type":"Organization","@id":"https:\/\/www.filmbuffonline.com\/FBOLNewsreel\/wordpress\/#organization","name":"FilmBuffOnline","description":"For The Complete Movie Fan","url":"https:\/\/www.filmbuffonline.com\/FBOLNewsreel\/wordpress\/","numberOfEmployees":{"@type":"QuantitativeValue","minValue":2,"maxValue":6},"logo":{"@type":"ImageObject","url":"https:\/\/www.filmbuffonline.com\/FBOLNewsreel\/wordpress\/wp-content\/uploads\/2020\/09\/FBOL-Reel.jpg","@id":"https:\/\/www.filmbuffonline.com\/FBOLNewsreel\/wordpress\/2012\/05\/14\/four-minute-amazing-spider-man-preview\/#organizationLogo","width":250,"height":250},"image":{"@id":"https:\/\/www.filmbuffonline.com\/FBOLNewsreel\/wordpress\/2012\/05\/14\/four-minute-amazing-spider-man-preview\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/FilmBuffOnline","https:\/\/twitter.com\/FilmBuffOnLine","https:\/\/www.youtube.com\/c\/Filmbuffonline\/featured"]},{"@type":"Person","@id":"https:\/\/www.filmbuffonline.com\/FBOLNewsreel\/wordpress\/author\/filmbuffrich\/#author","url":"https:\/\/www.filmbuffonline.com\/FBOLNewsreel\/wordpress\/author\/filmbuffrich\/","name":"Rich Drees","image":{"@type":"ImageObject","@id":"https:\/\/www.filmbuffonline.com\/FBOLNewsreel\/wordpress\/2012\/05\/14\/four-minute-amazing-spider-man-preview\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/0374c2a69ae003ff0a1eed863d0eb2cb98777ffc58bc6e7bb66aeaeb36ca3308?s=96&d=mm&r=r","width":96,"height":96,"caption":"Rich Drees"},"sameAs":["https:\/\/www.facebook.com\/FilmBuffRich\/","https:\/\/twitter.com\/FilmBuffRich"]},{"@type":"WebPage","@id":"https:\/\/www.filmbuffonline.com\/FBOLNewsreel\/wordpress\/2012\/05\/14\/four-minute-amazing-spider-man-preview\/#webpage","url":"https:\/\/www.filmbuffonline.com\/FBOLNewsreel\/wordpress\/2012\/05\/14\/four-minute-amazing-spider-man-preview\/","name":"Four Minute AMAZING SPIDER-MAN Preview","description":"See Spidey save a kid and fight the Lizard.","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/www.filmbuffonline.com\/FBOLNewsreel\/wordpress\/#website"},"breadcrumb":{"@id":"https:\/\/www.filmbuffonline.com\/FBOLNewsreel\/wordpress\/2012\/05\/14\/four-minute-amazing-spider-man-preview\/#breadcrumblist"},"author":{"@id":"https:\/\/www.filmbuffonline.com\/FBOLNewsreel\/wordpress\/author\/filmbuffrich\/#author"},"creator":{"@id":"https:\/\/www.filmbuffonline.com\/FBOLNewsreel\/wordpress\/author\/filmbuffrich\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/www.filmbuffonline.com\/FBOLNewsreel\/wordpress\/wp-content\/uploads\/2012\/05\/AmazingSpiderManTrailer.jpg","@id":"https:\/\/www.filmbuffonline.com\/FBOLNewsreel\/wordpress\/2012\/05\/14\/four-minute-amazing-spider-man-preview\/#mainImage","width":550,"height":265},"primaryImageOfPage":{"@id":"https:\/\/www.filmbuffonline.com\/FBOLNewsreel\/wordpress\/2012\/05\/14\/four-minute-amazing-spider-man-preview\/#mainImage"},"datePublished":"2012-05-14T22:51:58-04:00","dateModified":"2018-12-08T15:31:06-05:00"},{"@type":"WebSite","@id":"https:\/\/www.filmbuffonline.com\/FBOLNewsreel\/wordpress\/#website","url":"https:\/\/www.filmbuffonline.com\/FBOLNewsreel\/wordpress\/","name":"FilmBuffOnline","description":"For The Complete Movie Fan","inLanguage":"en-US","publisher":{"@id":"https:\/\/www.filmbuffonline.com\/FBOLNewsreel\/wordpress\/#organization"}}]},"og:locale":"en_US","og:site_name":"FilmBuffOnline","og:type":"article","og:title":"Four Minute AMAZING SPIDER-MAN Preview","og:description":"See Spidey save a kid and fight the Lizard.","og:url":"https:\/\/www.filmbuffonline.com\/FBOLNewsreel\/wordpress\/2012\/05\/14\/four-minute-amazing-spider-man-preview\/","fb:app_id":"278369843542253","fb:admins":"1588896122","og:image":"https:\/\/www.filmbuffonline.com\/FBOLNewsreel\/wordpress\/wp-content\/uploads\/2012\/05\/AmazingSpiderManTrailer.jpg","og:image:secure_url":"https:\/\/www.filmbuffonline.com\/FBOLNewsreel\/wordpress\/wp-content\/uploads\/2012\/05\/AmazingSpiderManTrailer.jpg","og:image:width":550,"og:image:height":265,"article:tag":["the amazing spider-man","marc webb","movie news"],"article:published_time":"2012-05-15T03:51:58+00:00","article:modified_time":"2018-12-08T20:31:06+00:00","article:publisher":"https:\/\/www.facebook.com\/FilmBuffOnline","article:author":"https:\/\/www.facebook.com\/FilmBuffRich\/","twitter:card":"summary_large_image","twitter:site":"@FilmBuffOnLine","twitter:title":"Four Minute AMAZING SPIDER-MAN Preview","twitter:description":"See Spidey save a kid and fight the Lizard.","twitter:creator":"@FilmBuffRich","twitter:image":"https:\/\/www.filmbuffonline.com\/FBOLNewsreel\/wordpress\/wp-content\/uploads\/2012\/05\/AmazingSpiderManTrailer.jpg"},"aioseo_meta_data":{"post_id":"20246","title":"Four Minute AMAZING SPIDER-MAN Preview","description":null,"keywords":[{"label":"The Amazing Spider-Man","value":"The Amazing Spider-Man"},{"label":"Marc Webb","value":"Marc Webb"}],"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":true,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"none","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-14 05:13:01","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2020-11-18 03:45:43","updated":"2026-05-14 05:13:01"},"nelio_content":{"autoShareEndMode":"never","automationSources":{"useCustomSentences":false,"customSentences":[]},"efiAlt":"","efiUrl":"","followers":[2],"highlights":[],"isAutoShareEnabled":false,"networkImageIds":[],"permalinkQueryArgs":[],"series":[],"suggestedReferences":[]},"_links":{"self":[{"href":"https:\/\/www.filmbuffonline.com\/FBOLNewsreel\/wordpress\/wp-json\/wp\/v2\/posts\/20246","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.filmbuffonline.com\/FBOLNewsreel\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.filmbuffonline.com\/FBOLNewsreel\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.filmbuffonline.com\/FBOLNewsreel\/wordpress\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.filmbuffonline.com\/FBOLNewsreel\/wordpress\/wp-json\/wp\/v2\/comments?post=20246"}],"version-history":[{"count":0,"href":"https:\/\/www.filmbuffonline.com\/FBOLNewsreel\/wordpress\/wp-json\/wp\/v2\/posts\/20246\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.filmbuffonline.com\/FBOLNewsreel\/wordpress\/wp-json\/wp\/v2\/media\/20249"}],"wp:attachment":[{"href":"https:\/\/www.filmbuffonline.com\/FBOLNewsreel\/wordpress\/wp-json\/wp\/v2\/media?parent=20246"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.filmbuffonline.com\/FBOLNewsreel\/wordpress\/wp-json\/wp\/v2\/categories?post=20246"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.filmbuffonline.com\/FBOLNewsreel\/wordpress\/wp-json\/wp\/v2\/tags?post=20246"},{"taxonomy":"series","embeddable":true,"href":"https:\/\/www.filmbuffonline.com\/FBOLNewsreel\/wordpress\/wp-json\/wp\/v2\/series?post=20246"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}