{"id":30580,"date":"2013-09-26T21:27:49","date_gmt":"2013-09-27T01:27:49","guid":{"rendered":"http:\/\/www.filmbuffonline.com\/FBOLNewsreel\/wordpress\/?p=30580"},"modified":"2018-12-08T23:22:28","modified_gmt":"2018-12-09T04:22:28","slug":"bryce-dallas-howard-jurassic-world","status":"publish","type":"post","link":"https:\/\/www.filmbuffonline.com\/FBOLNewsreel\/wordpress\/2013\/09\/26\/bryce-dallas-howard-jurassic-world\/","title":{"rendered":"Bryce Dallas Howard In Talks To Head To JURASSIC WORLD"},"content":{"rendered":"<p><a href=\"http:\/\/www.filmbuffonline.com\/FBOLNewsreel\/wordpress\/wp-content\/uploads\/2013\/09\/bryce-dallas-howard.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-30581\" alt=\"bryce-dallas-howard\" src=\"http:\/\/www.filmbuffonline.com\/FBOLNewsreel\/wordpress\/wp-content\/uploads\/2013\/09\/bryce-dallas-howard-230x300.jpg\" width=\"230\" height=\"300\" \/><\/a>Bryce Dallas Howard is currently in early talks to appear in <strong>Jurassic World<\/strong>, the long awaited fourth installment in the <strong>Jurassic Park<\/strong> franchise. <a href=\"http:\/\/www.thewrap.com\/bryce-dallas-howard-in-early-talks-to-star-in-universals-jurassic-world-exclusive\/\" target=\"_blank\">The Wrap<\/a> is reporting that although there had been rumors that she was in contention, but she was only extended an offer recently. This marks the first actual casting news for the sequel.<\/p>\n<p>Colin Trevorrow (<strong>Safety Not Guaranteed<\/strong>) is set to direct the fourth film in the franchise, which he wrote with frequent collaborator Derek Connolly. The is set for release in the busy summer of 2015 on June 12.<\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\">The first casting news for the sequel is finally here.<\/div>\n<p> <a class=\"mh-excerpt-more\" href=\"https:\/\/www.filmbuffonline.com\/FBOLNewsreel\/wordpress\/2013\/09\/26\/bryce-dallas-howard-jurassic-world\/\" title=\"Bryce Dallas Howard In Talks To Head To JURASSIC WORLD\">[click for more]<\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_ef_editorial_meta_date_first-draft-date":"","_ef_editorial_meta_paragraph_assignment":"","_ef_editorial_meta_checkbox_needs-photo":"","_ef_editorial_meta_number_word-count":"","footnotes":""},"categories":[84],"tags":[6736,6710],"series":[],"class_list":{"0":"post-30580","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-news","7":"tag-bruce-dallas-howard","8":"tag-jurassic-world"},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"The first casting news for the sequel is finally here.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Rich Drees\"\/>\n\t<meta name=\"google-site-verification\" content=\"wLC20yR0mPkWulQW1J3XdWt2N092dKXOxZCHsXSWa6A\" \/>\n\t<meta name=\"msvalidate.01\" content=\"7B67C6E6EDF5B3DC49380AB44DB9FDBF\" \/>\n\t<meta name=\"keywords\" content=\"bruce dallas howard,jurassic world,movie news\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.filmbuffonline.com\/FBOLNewsreel\/wordpress\/2013\/09\/26\/bryce-dallas-howard-jurassic-world\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"FilmBuffOnline\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Bryce Dallas Howard In Talks To Head To JURASSIC WORLD\" \/>\n\t\t<meta property=\"og:description\" content=\"The first casting news for the sequel is finally here.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.filmbuffonline.com\/FBOLNewsreel\/wordpress\/2013\/09\/26\/bryce-dallas-howard-jurassic-world\/\" \/>\n\t\t<meta property=\"fb:app_id\" content=\"278369843542253\" \/>\n\t\t<meta property=\"fb:admins\" content=\"1588896122\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.filmbuffonline.com\/FBOLNewsreel\/wordpress\/wp-content\/uploads\/2020\/09\/FBOL-Reel.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.filmbuffonline.com\/FBOLNewsreel\/wordpress\/wp-content\/uploads\/2020\/09\/FBOL-Reel.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"250\" \/>\n\t\t<meta property=\"og:image:height\" content=\"250\" \/>\n\t\t<meta property=\"article:tag\" content=\"bruce dallas howard\" \/>\n\t\t<meta property=\"article:tag\" content=\"jurassic world\" \/>\n\t\t<meta property=\"article:tag\" content=\"movie news\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2013-09-27T01:27:49+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2018-12-09T04:22:28+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/FilmBuffOnline\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/FilmBuffRich\/\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@FilmBuffOnLine\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Bryce Dallas Howard In Talks To Head To JURASSIC WORLD\" \/>\n\t\t<meta name=\"twitter:description\" content=\"The first casting news for the sequel is finally here.\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@FilmBuffRich\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.filmbuffonline.com\/FBOLNewsreel\/wordpress\/wp-content\/uploads\/2020\/09\/FBOL-Reel.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.filmbuffonline.com\\\/FBOLNewsreel\\\/wordpress\\\/2013\\\/09\\\/26\\\/bryce-dallas-howard-jurassic-world\\\/#article\",\"name\":\"Bryce Dallas Howard In Talks To Head To JURASSIC WORLD\",\"headline\":\"Bryce Dallas Howard In Talks To Head To JURASSIC WORLD\",\"author\":{\"@id\":\"https:\\\/\\\/www.filmbuffonline.com\\\/FBOLNewsreel\\\/wordpress\\\/author\\\/filmbuffrich\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.filmbuffonline.com\\\/FBOLNewsreel\\\/wordpress\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"http:\\\/\\\/www.filmbuffonline.com\\\/FBOLNewsreel\\\/wordpress\\\/wp-content\\\/uploads\\\/2013\\\/09\\\/bryce-dallas-howard-230x300.jpg\",\"@id\":\"https:\\\/\\\/www.filmbuffonline.com\\\/FBOLNewsreel\\\/wordpress\\\/2013\\\/09\\\/26\\\/bryce-dallas-howard-jurassic-world\\\/#articleImage\"},\"datePublished\":\"2013-09-26T21:27:49-04:00\",\"dateModified\":\"2018-12-08T23:22:28-05:00\",\"inLanguage\":\"en-US\",\"commentCount\":2,\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.filmbuffonline.com\\\/FBOLNewsreel\\\/wordpress\\\/2013\\\/09\\\/26\\\/bryce-dallas-howard-jurassic-world\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.filmbuffonline.com\\\/FBOLNewsreel\\\/wordpress\\\/2013\\\/09\\\/26\\\/bryce-dallas-howard-jurassic-world\\\/#webpage\"},\"articleSection\":\"Movie News, Bruce Dallas Howard, Jurassic World\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.filmbuffonline.com\\\/FBOLNewsreel\\\/wordpress\\\/2013\\\/09\\\/26\\\/bryce-dallas-howard-jurassic-world\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.filmbuffonline.com\\\/FBOLNewsreel\\\/wordpress#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.filmbuffonline.com\\\/FBOLNewsreel\\\/wordpress\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.filmbuffonline.com\\\/FBOLNewsreel\\\/wordpress\\\/category\\\/news\\\/#listItem\",\"name\":\"Movie News\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.filmbuffonline.com\\\/FBOLNewsreel\\\/wordpress\\\/category\\\/news\\\/#listItem\",\"position\":2,\"name\":\"Movie News\",\"item\":\"https:\\\/\\\/www.filmbuffonline.com\\\/FBOLNewsreel\\\/wordpress\\\/category\\\/news\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.filmbuffonline.com\\\/FBOLNewsreel\\\/wordpress\\\/2013\\\/09\\\/26\\\/bryce-dallas-howard-jurassic-world\\\/#listItem\",\"name\":\"Bryce Dallas Howard In Talks To Head To JURASSIC WORLD\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.filmbuffonline.com\\\/FBOLNewsreel\\\/wordpress#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.filmbuffonline.com\\\/FBOLNewsreel\\\/wordpress\\\/2013\\\/09\\\/26\\\/bryce-dallas-howard-jurassic-world\\\/#listItem\",\"position\":3,\"name\":\"Bryce Dallas Howard In Talks To Head To JURASSIC WORLD\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.filmbuffonline.com\\\/FBOLNewsreel\\\/wordpress\\\/category\\\/news\\\/#listItem\",\"name\":\"Movie News\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.filmbuffonline.com\\\/FBOLNewsreel\\\/wordpress\\\/#organization\",\"name\":\"FilmBuffOnline\",\"description\":\"For The Complete Movie Fan\",\"url\":\"https:\\\/\\\/www.filmbuffonline.com\\\/FBOLNewsreel\\\/wordpress\\\/\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":2,\"maxValue\":6},\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.filmbuffonline.com\\\/FBOLNewsreel\\\/wordpress\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/FBOL-Reel.jpg\",\"@id\":\"https:\\\/\\\/www.filmbuffonline.com\\\/FBOLNewsreel\\\/wordpress\\\/2013\\\/09\\\/26\\\/bryce-dallas-howard-jurassic-world\\\/#organizationLogo\",\"width\":250,\"height\":250},\"image\":{\"@id\":\"https:\\\/\\\/www.filmbuffonline.com\\\/FBOLNewsreel\\\/wordpress\\\/2013\\\/09\\\/26\\\/bryce-dallas-howard-jurassic-world\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/FilmBuffOnline\",\"https:\\\/\\\/twitter.com\\\/FilmBuffOnLine\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/Filmbuffonline\\\/featured\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.filmbuffonline.com\\\/FBOLNewsreel\\\/wordpress\\\/author\\\/filmbuffrich\\\/#author\",\"url\":\"https:\\\/\\\/www.filmbuffonline.com\\\/FBOLNewsreel\\\/wordpress\\\/author\\\/filmbuffrich\\\/\",\"name\":\"Rich Drees\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.filmbuffonline.com\\\/FBOLNewsreel\\\/wordpress\\\/2013\\\/09\\\/26\\\/bryce-dallas-howard-jurassic-world\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0374c2a69ae003ff0a1eed863d0eb2cb98777ffc58bc6e7bb66aeaeb36ca3308?s=96&d=mm&r=r\",\"width\":96,\"height\":96,\"caption\":\"Rich Drees\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/FilmBuffRich\\\/\",\"https:\\\/\\\/twitter.com\\\/FilmBuffRich\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.filmbuffonline.com\\\/FBOLNewsreel\\\/wordpress\\\/2013\\\/09\\\/26\\\/bryce-dallas-howard-jurassic-world\\\/#webpage\",\"url\":\"https:\\\/\\\/www.filmbuffonline.com\\\/FBOLNewsreel\\\/wordpress\\\/2013\\\/09\\\/26\\\/bryce-dallas-howard-jurassic-world\\\/\",\"name\":\"Bryce Dallas Howard In Talks To Head To JURASSIC WORLD\",\"description\":\"The first casting news for the sequel is finally here.\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.filmbuffonline.com\\\/FBOLNewsreel\\\/wordpress\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.filmbuffonline.com\\\/FBOLNewsreel\\\/wordpress\\\/2013\\\/09\\\/26\\\/bryce-dallas-howard-jurassic-world\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.filmbuffonline.com\\\/FBOLNewsreel\\\/wordpress\\\/author\\\/filmbuffrich\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.filmbuffonline.com\\\/FBOLNewsreel\\\/wordpress\\\/author\\\/filmbuffrich\\\/#author\"},\"datePublished\":\"2013-09-26T21:27:49-04:00\",\"dateModified\":\"2018-12-08T23:22:28-05:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.filmbuffonline.com\\\/FBOLNewsreel\\\/wordpress\\\/#website\",\"url\":\"https:\\\/\\\/www.filmbuffonline.com\\\/FBOLNewsreel\\\/wordpress\\\/\",\"name\":\"FilmBuffOnline\",\"description\":\"For The Complete Movie Fan\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.filmbuffonline.com\\\/FBOLNewsreel\\\/wordpress\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Bryce Dallas Howard In Talks To Head To JURASSIC WORLD<\/title>\n\n","aioseo_head_json":{"title":"Bryce Dallas Howard In Talks To Head To JURASSIC WORLD","description":"The first casting news for the sequel is finally here.","canonical_url":"https:\/\/www.filmbuffonline.com\/FBOLNewsreel\/wordpress\/2013\/09\/26\/bryce-dallas-howard-jurassic-world\/","robots":"max-image-preview:large","keywords":"bruce dallas howard,jurassic world,movie news","webmasterTools":{"google-site-verification":"wLC20yR0mPkWulQW1J3XdWt2N092dKXOxZCHsXSWa6A","msvalidate.01":"7B67C6E6EDF5B3DC49380AB44DB9FDBF","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.filmbuffonline.com\/FBOLNewsreel\/wordpress\/2013\/09\/26\/bryce-dallas-howard-jurassic-world\/#article","name":"Bryce Dallas Howard In Talks To Head To JURASSIC WORLD","headline":"Bryce Dallas Howard In Talks To Head To JURASSIC WORLD","author":{"@id":"https:\/\/www.filmbuffonline.com\/FBOLNewsreel\/wordpress\/author\/filmbuffrich\/#author"},"publisher":{"@id":"https:\/\/www.filmbuffonline.com\/FBOLNewsreel\/wordpress\/#organization"},"image":{"@type":"ImageObject","url":"http:\/\/www.filmbuffonline.com\/FBOLNewsreel\/wordpress\/wp-content\/uploads\/2013\/09\/bryce-dallas-howard-230x300.jpg","@id":"https:\/\/www.filmbuffonline.com\/FBOLNewsreel\/wordpress\/2013\/09\/26\/bryce-dallas-howard-jurassic-world\/#articleImage"},"datePublished":"2013-09-26T21:27:49-04:00","dateModified":"2018-12-08T23:22:28-05:00","inLanguage":"en-US","commentCount":2,"mainEntityOfPage":{"@id":"https:\/\/www.filmbuffonline.com\/FBOLNewsreel\/wordpress\/2013\/09\/26\/bryce-dallas-howard-jurassic-world\/#webpage"},"isPartOf":{"@id":"https:\/\/www.filmbuffonline.com\/FBOLNewsreel\/wordpress\/2013\/09\/26\/bryce-dallas-howard-jurassic-world\/#webpage"},"articleSection":"Movie News, Bruce Dallas Howard, Jurassic World"},{"@type":"BreadcrumbList","@id":"https:\/\/www.filmbuffonline.com\/FBOLNewsreel\/wordpress\/2013\/09\/26\/bryce-dallas-howard-jurassic-world\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.filmbuffonline.com\/FBOLNewsreel\/wordpress#listItem","position":1,"name":"Home","item":"https:\/\/www.filmbuffonline.com\/FBOLNewsreel\/wordpress","nextItem":{"@type":"ListItem","@id":"https:\/\/www.filmbuffonline.com\/FBOLNewsreel\/wordpress\/category\/news\/#listItem","name":"Movie News"}},{"@type":"ListItem","@id":"https:\/\/www.filmbuffonline.com\/FBOLNewsreel\/wordpress\/category\/news\/#listItem","position":2,"name":"Movie News","item":"https:\/\/www.filmbuffonline.com\/FBOLNewsreel\/wordpress\/category\/news\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.filmbuffonline.com\/FBOLNewsreel\/wordpress\/2013\/09\/26\/bryce-dallas-howard-jurassic-world\/#listItem","name":"Bryce Dallas Howard In Talks To Head To JURASSIC WORLD"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.filmbuffonline.com\/FBOLNewsreel\/wordpress#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.filmbuffonline.com\/FBOLNewsreel\/wordpress\/2013\/09\/26\/bryce-dallas-howard-jurassic-world\/#listItem","position":3,"name":"Bryce Dallas Howard In Talks To Head To JURASSIC WORLD","previousItem":{"@type":"ListItem","@id":"https:\/\/www.filmbuffonline.com\/FBOLNewsreel\/wordpress\/category\/news\/#listItem","name":"Movie News"}}]},{"@type":"Organization","@id":"https:\/\/www.filmbuffonline.com\/FBOLNewsreel\/wordpress\/#organization","name":"FilmBuffOnline","description":"For The Complete Movie Fan","url":"https:\/\/www.filmbuffonline.com\/FBOLNewsreel\/wordpress\/","numberOfEmployees":{"@type":"QuantitativeValue","minValue":2,"maxValue":6},"logo":{"@type":"ImageObject","url":"https:\/\/www.filmbuffonline.com\/FBOLNewsreel\/wordpress\/wp-content\/uploads\/2020\/09\/FBOL-Reel.jpg","@id":"https:\/\/www.filmbuffonline.com\/FBOLNewsreel\/wordpress\/2013\/09\/26\/bryce-dallas-howard-jurassic-world\/#organizationLogo","width":250,"height":250},"image":{"@id":"https:\/\/www.filmbuffonline.com\/FBOLNewsreel\/wordpress\/2013\/09\/26\/bryce-dallas-howard-jurassic-world\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/FilmBuffOnline","https:\/\/twitter.com\/FilmBuffOnLine","https:\/\/www.youtube.com\/c\/Filmbuffonline\/featured"]},{"@type":"Person","@id":"https:\/\/www.filmbuffonline.com\/FBOLNewsreel\/wordpress\/author\/filmbuffrich\/#author","url":"https:\/\/www.filmbuffonline.com\/FBOLNewsreel\/wordpress\/author\/filmbuffrich\/","name":"Rich Drees","image":{"@type":"ImageObject","@id":"https:\/\/www.filmbuffonline.com\/FBOLNewsreel\/wordpress\/2013\/09\/26\/bryce-dallas-howard-jurassic-world\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/0374c2a69ae003ff0a1eed863d0eb2cb98777ffc58bc6e7bb66aeaeb36ca3308?s=96&d=mm&r=r","width":96,"height":96,"caption":"Rich Drees"},"sameAs":["https:\/\/www.facebook.com\/FilmBuffRich\/","https:\/\/twitter.com\/FilmBuffRich"]},{"@type":"WebPage","@id":"https:\/\/www.filmbuffonline.com\/FBOLNewsreel\/wordpress\/2013\/09\/26\/bryce-dallas-howard-jurassic-world\/#webpage","url":"https:\/\/www.filmbuffonline.com\/FBOLNewsreel\/wordpress\/2013\/09\/26\/bryce-dallas-howard-jurassic-world\/","name":"Bryce Dallas Howard In Talks To Head To JURASSIC WORLD","description":"The first casting news for the sequel is finally here.","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/www.filmbuffonline.com\/FBOLNewsreel\/wordpress\/#website"},"breadcrumb":{"@id":"https:\/\/www.filmbuffonline.com\/FBOLNewsreel\/wordpress\/2013\/09\/26\/bryce-dallas-howard-jurassic-world\/#breadcrumblist"},"author":{"@id":"https:\/\/www.filmbuffonline.com\/FBOLNewsreel\/wordpress\/author\/filmbuffrich\/#author"},"creator":{"@id":"https:\/\/www.filmbuffonline.com\/FBOLNewsreel\/wordpress\/author\/filmbuffrich\/#author"},"datePublished":"2013-09-26T21:27:49-04:00","dateModified":"2018-12-08T23:22:28-05:00"},{"@type":"WebSite","@id":"https:\/\/www.filmbuffonline.com\/FBOLNewsreel\/wordpress\/#website","url":"https:\/\/www.filmbuffonline.com\/FBOLNewsreel\/wordpress\/","name":"FilmBuffOnline","description":"For The Complete Movie Fan","inLanguage":"en-US","publisher":{"@id":"https:\/\/www.filmbuffonline.com\/FBOLNewsreel\/wordpress\/#organization"}}]},"og:locale":"en_US","og:site_name":"FilmBuffOnline","og:type":"article","og:title":"Bryce Dallas Howard In Talks To Head To JURASSIC WORLD","og:description":"The first casting news for the sequel is finally here.","og:url":"https:\/\/www.filmbuffonline.com\/FBOLNewsreel\/wordpress\/2013\/09\/26\/bryce-dallas-howard-jurassic-world\/","fb:app_id":"278369843542253","fb:admins":"1588896122","og:image":"https:\/\/www.filmbuffonline.com\/FBOLNewsreel\/wordpress\/wp-content\/uploads\/2020\/09\/FBOL-Reel.jpg","og:image:secure_url":"https:\/\/www.filmbuffonline.com\/FBOLNewsreel\/wordpress\/wp-content\/uploads\/2020\/09\/FBOL-Reel.jpg","og:image:width":250,"og:image:height":250,"article:tag":["bruce dallas howard","jurassic world","movie news"],"article:published_time":"2013-09-27T01:27:49+00:00","article:modified_time":"2018-12-09T04:22:28+00:00","article:publisher":"https:\/\/www.facebook.com\/FilmBuffOnline","article:author":"https:\/\/www.facebook.com\/FilmBuffRich\/","twitter:card":"summary_large_image","twitter:site":"@FilmBuffOnLine","twitter:title":"Bryce Dallas Howard In Talks To Head To JURASSIC WORLD","twitter:description":"The first casting news for the sequel is finally here.","twitter:creator":"@FilmBuffRich","twitter:image":"https:\/\/www.filmbuffonline.com\/FBOLNewsreel\/wordpress\/wp-content\/uploads\/2020\/09\/FBOL-Reel.jpg"},"aioseo_meta_data":{"post_id":"30580","title":"Bryce Dallas Howard In Talks To Head To JURASSIC WORLD","description":null,"keywords":[{"label":"Bruce Dallas Howard","value":"Bruce Dallas Howard"},{"label":"Jurassic World","value":"Jurassic World"}],"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":true,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"none","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-14 14:39:32","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2020-11-18 03:45:51","updated":"2026-05-14 14:39:32"},"nelio_content":{"autoShareEndMode":"never","automationSources":{"useCustomSentences":false,"customSentences":[]},"efiAlt":"","efiUrl":"","followers":[2],"highlights":[],"isAutoShareEnabled":false,"networkImageIds":[],"permalinkQueryArgs":[],"series":[],"suggestedReferences":[]},"_links":{"self":[{"href":"https:\/\/www.filmbuffonline.com\/FBOLNewsreel\/wordpress\/wp-json\/wp\/v2\/posts\/30580","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.filmbuffonline.com\/FBOLNewsreel\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.filmbuffonline.com\/FBOLNewsreel\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.filmbuffonline.com\/FBOLNewsreel\/wordpress\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.filmbuffonline.com\/FBOLNewsreel\/wordpress\/wp-json\/wp\/v2\/comments?post=30580"}],"version-history":[{"count":0,"href":"https:\/\/www.filmbuffonline.com\/FBOLNewsreel\/wordpress\/wp-json\/wp\/v2\/posts\/30580\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.filmbuffonline.com\/FBOLNewsreel\/wordpress\/wp-json\/wp\/v2\/media?parent=30580"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.filmbuffonline.com\/FBOLNewsreel\/wordpress\/wp-json\/wp\/v2\/categories?post=30580"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.filmbuffonline.com\/FBOLNewsreel\/wordpress\/wp-json\/wp\/v2\/tags?post=30580"},{"taxonomy":"series","embeddable":true,"href":"https:\/\/www.filmbuffonline.com\/FBOLNewsreel\/wordpress\/wp-json\/wp\/v2\/series?post=30580"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}